{"id":882094,"date":"2025-11-27T10:34:07","date_gmt":"2025-11-27T09:34:07","guid":{"rendered":"https:\/\/polovnemasine.rs\/?p=882094"},"modified":"2025-12-01T12:26:55","modified_gmt":"2025-12-01T11:26:55","slug":"jelsingrad-makaze-za-lim","status":"publish","type":"post","link":"https:\/\/polovnemasine.rs\/sr\/jelsingrad-makaze-za-lim\/","title":{"rendered":"JEL\u0160INGRAD Makaze za lim"},"content":{"rendered":"<p>JEL\u0160INGRAD Makaze za lim.<br \/>\nMarka: Jel\u0161ingrad, model M 5A.<br \/>\nRadna du\u017eina: 2500 mm.<br \/>\nDebljina se\u010denja: 5 mm.<br \/>\nSnaga motora: 10 KS (7,5 kW), brzina 1440 ob\/min.<br \/>\nBrzina rada: 48 udara alata u minuti.<br \/>\nGodina proizvodnje: 1976.<br \/>\nTe\u017eina: 4400 Kg.<br \/>\nPolovno, doma\u0107e proizvodnje.<\/p>\n\r\n                <style type=\"text\/css\">\r\n                    \r\n                    #tdi_1  .td-doubleSlider-2 .td-item1 {\r\n                        background: url(https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-2-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #tdi_1  .td-doubleSlider-2 .td-item2 {\r\n                        background: url(https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-5-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #tdi_1  .td-doubleSlider-2 .td-item3 {\r\n                        background: url(https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-3-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                <\/style>\r\n\r\n                <div id=\"tdi_1\" class=\"td-gallery td-slide-on-2-columns\">\r\n                    <div class=\"post_td_gallery\">\r\n                        <div class=\"td-gallery-slide-top\">\r\n                           <div class=\"td-gallery-title\">JEL\u0160INGRAD Makaze za lim<\/div>\r\n\r\n                            <div class=\"td-gallery-controls-wrapper\">\r\n                                <div class=\"td-gallery-slide-count\"><span class=\"td-gallery-slide-item-focus\">1<\/span> of 3<\/div>\r\n                                <div class=\"td-gallery-slide-prev-next-but\">\r\n                                    <i class = \"td-icon-left doubleSliderPrevButton\"><\/i>\r\n                                    <i class = \"td-icon-right doubleSliderNextButton\"><\/i>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-1 \">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-slide-item td-item1\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-2.jpg\" title=\"JEL\u0160INGRAD Makaze za lim\"  data-caption=\"\"  data-description=\"Godina proizvodnje: 1976.\">\r\n                                <img decoding=\"async\" src=\"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-2-560x420.jpg\" srcset=\"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-2-560x420.jpg 560w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-2-400x300.jpg 400w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-2-200x150.jpg 200w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-2-80x60.jpg 80w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-2-150x113.jpg 150w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-2-300x225.jpg 300w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-2-696x522.jpg 696w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-2-265x198.jpg 265w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-2.jpg 800w\" sizes=\"(max-width: 560px) 100vw, 560px\" alt=\"Machine tech data\">\r\n                            <\/a>\r\n                            <figcaption class = \"td-slide-caption td-gallery-slide-content\"><span>Godina proizvodnje: 1976.<\/span><\/figcaption>\r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item2\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-5.jpg\" title=\"JEL\u0160INGRAD Makaze za lim\"  data-caption=\"\"  data-description=\"Debljina se\u010denja lima: 5 mm.\">\r\n                                <img decoding=\"async\" src=\"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-5-560x420.jpg\" srcset=\"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-5-560x420.jpg 560w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-5-400x300.jpg 400w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-5-200x150.jpg 200w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-5-80x60.jpg 80w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-5-150x113.jpg 150w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-5-300x225.jpg 300w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-5-696x522.jpg 696w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-5-265x198.jpg 265w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-5.jpg 800w\" sizes=\"(max-width: 560px) 100vw, 560px\" alt=\"JEL&Scaron;INGRAD Makaze za lim\">\r\n                            <\/a>\r\n                            <figcaption class = \"td-slide-caption td-gallery-slide-content\"><span>Debljina se\u010denja lima: 5 mm.<\/span><\/figcaption>\r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item3\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-3.jpg\" title=\"JEL\u0160INGRAD Makaze za lim\"  data-caption=\"\"  data-description=\"Radna brzina: 48 udara alata u minuti.\">\r\n                                <img decoding=\"async\" src=\"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-3-560x420.jpg\" srcset=\"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-3-560x420.jpg 560w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-3-400x300.jpg 400w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-3-200x150.jpg 200w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-3-80x60.jpg 80w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-3-150x113.jpg 150w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-3-300x225.jpg 300w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-3-696x522.jpg 696w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-3-265x198.jpg 265w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-3.jpg 800w\" sizes=\"(max-width: 560px) 100vw, 560px\" alt=\"Machine tech data\">\r\n                            <\/a>\r\n                            <figcaption class = \"td-slide-caption td-gallery-slide-content\"><span>Radna brzina: 48 udara alata u minuti.<\/span><\/figcaption>\r\n                        <\/figure>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-2\">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-button td-item1\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item2\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item3\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n                \n<p>JEL\u0160INGRAD Makaze za lim se nalaz\u0435 u <a href=\"https:\/\/www.youtube.com\/watch?v=OAvzarsNNb4&#038;t=94s\" target=\"_blank\">Ma\u010dvanskoj Mitrovici<\/a>, ulica \u017darka Vu\u010dinic\u0301a 32B (deo grada Sremska Mitrovica), Srbija. Ma\u0161ina je u odli\u010dnom stanju i mo\u017ee se testirati u radu. Transport pada na ra\u010dun klijenta, a ova <strong>giljotina za lim<\/strong> c\u0301e se besplatno utovariti u transportno vozilo klijenta, posle obavljene kupovine u na\u0161oj kompaniji. <strong>Apokalipsa d.o.o.<\/strong> ima preko 2.500 polovnih, remontovanih ma\u0161ina na lageru. Sve ma\u0161ine mo\u017eete pogledati i isprobati u halama preduze\u0107a. Ma\u0161ine su ve\u0107inom Italijanske proizvodnje, od livenog \u010delika. Imamo u ponudi kompletne linije za proizvodnju drvenih gajbi marke Corali. Komplet linije za proizvodnju: name\u0161taja, peleta, paleta, drvenih vrata i prozora, kao i parketa. <\/p>\n<p><a href=\"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-4.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-4.jpg\" alt=\"JEL\u0160INGRAD Makaze za lim\" width=\"800\" height=\"600\" class=\"aligncenter size-full wp-image-882080\" srcset=\"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-4.jpg 800w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-4-400x300.jpg 400w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-4-200x150.jpg 200w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-4-560x420.jpg 560w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-4-80x60.jpg 80w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-4-150x113.jpg 150w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-4-300x225.jpg 300w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-4-696x522.jpg 696w, https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-4-265x198.jpg 265w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>JEL\u0160INGRAD Makaze za lim. Marka: Jel\u0161ingrad, model M 5A. Radna du\u017eina: 2500 mm. Debljina se\u010denja: 5 mm. Snaga motora: 10 KS (7,5 kW), brzina 1440 ob\/min. Brzina rada: 48 udara alata u minuti. Godina proizvodnje: 1976. Te\u017eina: 4400 Kg. Polovno, doma\u0107e proizvodnje. JEL\u0160INGRAD Makaze za lim se nalaz\u0435 u Ma\u010dvanskoj Mitrovici, ulica \u017darka Vu\u010dinic\u0301a 32B [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":882092,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[944,18],"tags":[7855,8414],"class_list":{"0":"post-882094","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-makaze-za-lim","8":"category-masine-za-obradu-metala","9":"tag-guillotine-shear","10":"tag-jelsingrad-2500-5"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JEL\u0160INGRAD Makaze za lim | Apokalipsa d.o.o. - Srbija.<\/title>\n<meta name=\"description\" content=\"JEL\u0160INGRAD Makaze za lim 2500\/5 | Radna du\u017eina: 2500 mm. | Apokalipsa d.o.o. - na lageru ima preko 2.500 polovnih ma\u0161ina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/polovnemasine.rs\/sr\/jelsingrad-makaze-za-lim\/\" \/>\n<meta property=\"og:locale\" content=\"sr_RS\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JEL\u0160INGRAD Makaze za lim | Apokalipsa d.o.o. - Srbija.\" \/>\n<meta property=\"og:description\" content=\"JEL\u0160INGRAD Makaze za lim 2500\/5 | Radna du\u017eina: 2500 mm. | Apokalipsa d.o.o. - na lageru ima preko 2.500 polovnih ma\u0161ina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/polovnemasine.rs\/sr\/jelsingrad-makaze-za-lim\/\" \/>\n<meta property=\"og:site_name\" content=\"Apokalipsa d.o.o.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MarketingMasina\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-27T09:34:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-01T11:26:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Polovne Ma\u0161ine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u043e\u0434\" \/>\n\t<meta name=\"twitter:data1\" content=\"Polovne Ma\u0161ine\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u041f\u0440\u043e\u0446\u0435\u045a\u0435\u043d\u043e \u0432\u0440\u0435\u043c\u0435 \u0447\u0438\u0442\u0430\u045a\u0430\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/jelsingrad-makaze-za-lim\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/jelsingrad-makaze-za-lim\\\/\"},\"author\":{\"name\":\"Polovne Ma\u0161ine\",\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/#\\\/schema\\\/person\\\/67f851cdc74575fbdd1b436d0155fc3f\"},\"headline\":\"JEL\u0160INGRAD Makaze za lim\",\"datePublished\":\"2025-11-27T09:34:07+00:00\",\"dateModified\":\"2025-12-01T11:26:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/jelsingrad-makaze-za-lim\\\/\"},\"wordCount\":189,\"publisher\":{\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/jelsingrad-makaze-za-lim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/polovnemasine.rs\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Makaze-za-lim-JELSINGRAD-1.jpg\",\"keywords\":[\"guillotine shear\",\"Jel\u0161ingrad 2500\\\/5\"],\"articleSection\":[\"Makaze za lim\",\"Ma\u0161ine za obradu metala\"],\"inLanguage\":\"sr-RS\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/jelsingrad-makaze-za-lim\\\/\",\"url\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/jelsingrad-makaze-za-lim\\\/\",\"name\":\"JEL\u0160INGRAD Makaze za lim | Apokalipsa d.o.o. - Srbija.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/jelsingrad-makaze-za-lim\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/jelsingrad-makaze-za-lim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/polovnemasine.rs\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Makaze-za-lim-JELSINGRAD-1.jpg\",\"datePublished\":\"2025-11-27T09:34:07+00:00\",\"dateModified\":\"2025-12-01T11:26:55+00:00\",\"description\":\"JEL\u0160INGRAD Makaze za lim 2500\\\/5 | Radna du\u017eina: 2500 mm. | Apokalipsa d.o.o. - na lageru ima preko 2.500 polovnih ma\u0161ina.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/jelsingrad-makaze-za-lim\\\/#breadcrumb\"},\"inLanguage\":\"sr-RS\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/jelsingrad-makaze-za-lim\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sr-RS\",\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/jelsingrad-makaze-za-lim\\\/#primaryimage\",\"url\":\"https:\\\/\\\/polovnemasine.rs\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Makaze-za-lim-JELSINGRAD-1.jpg\",\"contentUrl\":\"https:\\\/\\\/polovnemasine.rs\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Makaze-za-lim-JELSINGRAD-1.jpg\",\"width\":800,\"height\":600,\"caption\":\"JEL\u0160INGRAD Makaze za lim\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/jelsingrad-makaze-za-lim\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna\",\"item\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Metalworking Machines\",\"item\":\"https:\\\/\\\/polovnemasine.rs\\\/en\\\/category\\\/metalworking-machines\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Guillottine shear\",\"item\":\"https:\\\/\\\/polovnemasine.rs\\\/en\\\/category\\\/metalworking-machines\\\/guillottine-shear\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"JEL\u0160INGRAD Makaze za lim\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/#website\",\"url\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/\",\"name\":\"Apokalipsa d.o.o.\",\"description\":\"POLOVNE MA\u0160INE\",\"publisher\":{\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/#organization\"},\"alternateName\":\"Polovne ma\u0161ine Srbija\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sr-RS\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/#organization\",\"name\":\"Apokalipsa Ltd - Sremska Mitrovica\",\"alternateName\":\"Polovne ma\u0161ine Srbija\",\"url\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sr-RS\",\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/polovnemasine.rs\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Logo-Apokalipsa-d.o.o-web.png\",\"contentUrl\":\"https:\\\/\\\/polovnemasine.rs\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Logo-Apokalipsa-d.o.o-web.png\",\"width\":512,\"height\":512,\"caption\":\"Apokalipsa Ltd - Sremska Mitrovica\"},\"image\":{\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MarketingMasina\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/#\\\/schema\\\/person\\\/67f851cdc74575fbdd1b436d0155fc3f\",\"name\":\"Polovne Ma\u0161ine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sr-RS\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d8f16a0ce4d5f7adb9e962bf20271acaba66ac4dd34876222e559f9abdb1ec1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d8f16a0ce4d5f7adb9e962bf20271acaba66ac4dd34876222e559f9abdb1ec1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d8f16a0ce4d5f7adb9e962bf20271acaba66ac4dd34876222e559f9abdb1ec1?s=96&d=mm&r=g\",\"caption\":\"Polovne Ma\u0161ine\"},\"url\":\"https:\\\/\\\/polovnemasine.rs\\\/sr\\\/author\\\/apokalipsa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JEL\u0160INGRAD Makaze za lim | Apokalipsa d.o.o. - Srbija.","description":"JEL\u0160INGRAD Makaze za lim 2500\/5 | Radna du\u017eina: 2500 mm. | Apokalipsa d.o.o. - na lageru ima preko 2.500 polovnih ma\u0161ina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/polovnemasine.rs\/sr\/jelsingrad-makaze-za-lim\/","og_locale":"sr_RS","og_type":"article","og_title":"JEL\u0160INGRAD Makaze za lim | Apokalipsa d.o.o. - Srbija.","og_description":"JEL\u0160INGRAD Makaze za lim 2500\/5 | Radna du\u017eina: 2500 mm. | Apokalipsa d.o.o. - na lageru ima preko 2.500 polovnih ma\u0161ina.","og_url":"https:\/\/polovnemasine.rs\/sr\/jelsingrad-makaze-za-lim\/","og_site_name":"Apokalipsa d.o.o.","article_publisher":"https:\/\/www.facebook.com\/MarketingMasina","article_published_time":"2025-11-27T09:34:07+00:00","article_modified_time":"2025-12-01T11:26:55+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-1.jpg","type":"image\/jpeg"}],"author":"Polovne Ma\u0161ine","twitter_card":"summary_large_image","twitter_misc":{"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u043e\u0434":"Polovne Ma\u0161ine","\u041f\u0440\u043e\u0446\u0435\u045a\u0435\u043d\u043e \u0432\u0440\u0435\u043c\u0435 \u0447\u0438\u0442\u0430\u045a\u0430":"1 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/polovnemasine.rs\/sr\/jelsingrad-makaze-za-lim\/#article","isPartOf":{"@id":"https:\/\/polovnemasine.rs\/sr\/jelsingrad-makaze-za-lim\/"},"author":{"name":"Polovne Ma\u0161ine","@id":"https:\/\/polovnemasine.rs\/sr\/#\/schema\/person\/67f851cdc74575fbdd1b436d0155fc3f"},"headline":"JEL\u0160INGRAD Makaze za lim","datePublished":"2025-11-27T09:34:07+00:00","dateModified":"2025-12-01T11:26:55+00:00","mainEntityOfPage":{"@id":"https:\/\/polovnemasine.rs\/sr\/jelsingrad-makaze-za-lim\/"},"wordCount":189,"publisher":{"@id":"https:\/\/polovnemasine.rs\/sr\/#organization"},"image":{"@id":"https:\/\/polovnemasine.rs\/sr\/jelsingrad-makaze-za-lim\/#primaryimage"},"thumbnailUrl":"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-1.jpg","keywords":["guillotine shear","Jel\u0161ingrad 2500\/5"],"articleSection":["Makaze za lim","Ma\u0161ine za obradu metala"],"inLanguage":"sr-RS"},{"@type":"WebPage","@id":"https:\/\/polovnemasine.rs\/sr\/jelsingrad-makaze-za-lim\/","url":"https:\/\/polovnemasine.rs\/sr\/jelsingrad-makaze-za-lim\/","name":"JEL\u0160INGRAD Makaze za lim | Apokalipsa d.o.o. - Srbija.","isPartOf":{"@id":"https:\/\/polovnemasine.rs\/sr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/polovnemasine.rs\/sr\/jelsingrad-makaze-za-lim\/#primaryimage"},"image":{"@id":"https:\/\/polovnemasine.rs\/sr\/jelsingrad-makaze-za-lim\/#primaryimage"},"thumbnailUrl":"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-1.jpg","datePublished":"2025-11-27T09:34:07+00:00","dateModified":"2025-12-01T11:26:55+00:00","description":"JEL\u0160INGRAD Makaze za lim 2500\/5 | Radna du\u017eina: 2500 mm. | Apokalipsa d.o.o. - na lageru ima preko 2.500 polovnih ma\u0161ina.","breadcrumb":{"@id":"https:\/\/polovnemasine.rs\/sr\/jelsingrad-makaze-za-lim\/#breadcrumb"},"inLanguage":"sr-RS","potentialAction":[{"@type":"ReadAction","target":["https:\/\/polovnemasine.rs\/sr\/jelsingrad-makaze-za-lim\/"]}]},{"@type":"ImageObject","inLanguage":"sr-RS","@id":"https:\/\/polovnemasine.rs\/sr\/jelsingrad-makaze-za-lim\/#primaryimage","url":"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-1.jpg","contentUrl":"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2016\/12\/Makaze-za-lim-JELSINGRAD-1.jpg","width":800,"height":600,"caption":"JEL\u0160INGRAD Makaze za lim"},{"@type":"BreadcrumbList","@id":"https:\/\/polovnemasine.rs\/sr\/jelsingrad-makaze-za-lim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna","item":"https:\/\/polovnemasine.rs\/sr\/"},{"@type":"ListItem","position":2,"name":"Metalworking Machines","item":"https:\/\/polovnemasine.rs\/en\/category\/metalworking-machines\/"},{"@type":"ListItem","position":3,"name":"Guillottine shear","item":"https:\/\/polovnemasine.rs\/en\/category\/metalworking-machines\/guillottine-shear\/"},{"@type":"ListItem","position":4,"name":"JEL\u0160INGRAD Makaze za lim"}]},{"@type":"WebSite","@id":"https:\/\/polovnemasine.rs\/sr\/#website","url":"https:\/\/polovnemasine.rs\/sr\/","name":"Apokalipsa d.o.o.","description":"POLOVNE MA\u0160INE","publisher":{"@id":"https:\/\/polovnemasine.rs\/sr\/#organization"},"alternateName":"Polovne ma\u0161ine Srbija","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/polovnemasine.rs\/sr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sr-RS"},{"@type":"Organization","@id":"https:\/\/polovnemasine.rs\/sr\/#organization","name":"Apokalipsa Ltd - Sremska Mitrovica","alternateName":"Polovne ma\u0161ine Srbija","url":"https:\/\/polovnemasine.rs\/sr\/","logo":{"@type":"ImageObject","inLanguage":"sr-RS","@id":"https:\/\/polovnemasine.rs\/sr\/#\/schema\/logo\/image\/","url":"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2021\/12\/Logo-Apokalipsa-d.o.o-web.png","contentUrl":"https:\/\/polovnemasine.rs\/wp-content\/uploads\/2021\/12\/Logo-Apokalipsa-d.o.o-web.png","width":512,"height":512,"caption":"Apokalipsa Ltd - Sremska Mitrovica"},"image":{"@id":"https:\/\/polovnemasine.rs\/sr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MarketingMasina"]},{"@type":"Person","@id":"https:\/\/polovnemasine.rs\/sr\/#\/schema\/person\/67f851cdc74575fbdd1b436d0155fc3f","name":"Polovne Ma\u0161ine","image":{"@type":"ImageObject","inLanguage":"sr-RS","@id":"https:\/\/secure.gravatar.com\/avatar\/0d8f16a0ce4d5f7adb9e962bf20271acaba66ac4dd34876222e559f9abdb1ec1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0d8f16a0ce4d5f7adb9e962bf20271acaba66ac4dd34876222e559f9abdb1ec1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d8f16a0ce4d5f7adb9e962bf20271acaba66ac4dd34876222e559f9abdb1ec1?s=96&d=mm&r=g","caption":"Polovne Ma\u0161ine"},"url":"https:\/\/polovnemasine.rs\/sr\/author\/apokalipsa\/"}]}},"_links":{"self":[{"href":"https:\/\/polovnemasine.rs\/sr\/wp-json\/wp\/v2\/posts\/882094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/polovnemasine.rs\/sr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/polovnemasine.rs\/sr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/polovnemasine.rs\/sr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/polovnemasine.rs\/sr\/wp-json\/wp\/v2\/comments?post=882094"}],"version-history":[{"count":4,"href":"https:\/\/polovnemasine.rs\/sr\/wp-json\/wp\/v2\/posts\/882094\/revisions"}],"predecessor-version":[{"id":882177,"href":"https:\/\/polovnemasine.rs\/sr\/wp-json\/wp\/v2\/posts\/882094\/revisions\/882177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/polovnemasine.rs\/sr\/wp-json\/wp\/v2\/media\/882092"}],"wp:attachment":[{"href":"https:\/\/polovnemasine.rs\/sr\/wp-json\/wp\/v2\/media?parent=882094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/polovnemasine.rs\/sr\/wp-json\/wp\/v2\/categories?post=882094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/polovnemasine.rs\/sr\/wp-json\/wp\/v2\/tags?post=882094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}